{"id":255,"date":"2021-03-13T23:41:19","date_gmt":"2021-03-13T23:41:19","guid":{"rendered":"https:\/\/enterateconginettluces.com\/?p=255"},"modified":"2021-03-14T00:08:32","modified_gmt":"2021-03-14T00:08:32","slug":"atencion-medica-y-aca-ley-de-seguro-de-salud-con-el-american-rescue-plan","status":"publish","type":"post","link":"http:\/\/ezratewithrussellscott.com\/en\/2021\/03\/13\/atencion-medica-y-aca-ley-de-seguro-de-salud-con-el-american-rescue-plan\/","title":{"rendered":"Ley de Seguro de salud (ACA) y el American Rescue Plan"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img src=\"https:\/\/enterateconginettluces.com\/wp-content\/uploads\/2021\/03\/Aca-y-la-Ley-Covid-1024x1024.jpeg\" alt=\"Ley de alivio por covid 19\" class=\"wp-image-254\"\/><\/figure>\n\n\n\n<p>El presidente Biden promulg\u00f3 la Ley del Plan de Rescate Estadounidense de 2021 (ARP) el 11 de marzo de 2021. Esta Ley realizara mejoras importantes en el acceso y la asequibilidad de la cobertura m\u00e9dica a trav\u00e9s del Mercado al aumentar la elegibilidad para asistencia financiera para ayudar a pagar la cobertura del Mercado.<\/p>\n\n\n\n<p>La nueva ley reducir\u00e1 las primas para la mayor\u00eda de las personas que actualmente tienen un plan de salud del Mercado y ampliar\u00e1 el acceso a la asistencia financiera para m\u00e1s consumidores.<\/p>\n\n\n\n<p>Bajo la nueva ley, muchas personas que compran su propio seguro m\u00e9dico directamente a trav\u00e9s del Mercado ser\u00e1n elegibles para recibir mayores cr\u00e9ditos fiscales para reducir sus primas. A partir del 1 de abril de 2021, los consumidores que se inscriban en la cobertura del Mercado a trav\u00e9s de CuidadoDeSalud.gov podr\u00e1n aprovechar estos mayores ahorros y menores costos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Bajo el Plan de Rescate Americano:<\/strong><br>Las personas y las familias pueden ser elegibles para un aumento temporal en los cr\u00e9ditos fiscales para las primas para este a\u00f1o, sin que nadie pague m\u00e1s del 8.5% de sus ingresos familiares para el costo del plan de referencia o un plan menos costoso. Es decir, muchos consumidores ser\u00e1n elegibles para montos de cr\u00e9dito tributario m\u00e1s altos para ayudar a cubrir las primas de sus planes de salud del Mercado.<\/p>\n\n\n\n<p>Los contribuyentes que reciben compensaci\u00f3n por desempleo durante cualquier semana a partir de 2021 pueden ser elegibles para recibir cr\u00e9ditos fiscales para las primas para ayudar a pagar la cobertura del Mercado de 2021.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente Biden promulg\u00f3 la Ley del Plan de Rescate Estadounidense de 2021 (ARP) el 11 de marzo de 2021. Esta Ley realizara mejoras importantes en el acceso y la asequibilidad de la cobertura m\u00e9dica a trav\u00e9s del Mercado al aumentar la elegibilidad para asistencia financiera para ayudar a pagar la cobertura del Mercado. La [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/posts\/255"}],"collection":[{"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":4,"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/posts\/255\/revisions"}],"predecessor-version":[{"id":260,"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/posts\/255\/revisions\/260"}],"wp:attachment":[{"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/media?parent=255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/categories?post=255"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ezratewithrussellscott.com\/en\/wp-json\/wp\/v2\/tags?post=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}